{"id":685,"count":5,"description":"<h2>Twyman-Green Interferometer<\/h2>\r\n\r\n<hr data-start=\"3469\" data-end=\"3472\" \/>\r\n\r\nThe Twyman-Green interferometers from <strong>4D Technology<\/strong> are high-precision optical measuring instruments that are used in a variety of ways in science and industry. They are specially designed for measuring wavefronts and analyzing optical components. With their ability to detect even the smallest deviations in the optics, these interferometers ensure outstanding quality and reliability in every application.\r\n\r\n<a href=\"https:\/\/soliton-gmbh.de\/wp-content\/uploads\/2024\/08\/4D15.jpg\"><img class=\"alignnone wp-image-9423 size-large\" src=\"https:\/\/soliton-gmbh.de\/wp-content\/uploads\/2024\/08\/4D15-1024x576.jpg\" alt=\"Phasecam JWST\" width=\"1024\" height=\"576\" \/><\/a>\r\n\r\n<strong><em>Here the use of a PhaseCam in the measurement of the James Webb Space Telescope (JWST) primary mirror.<\/em><\/strong>\r\n\r\n<em><a href=\"https:\/\/soliton-gmbh.de\/wp-content\/uploads\/2024\/08\/4dtechnology-Logo.png\"><img class=\"alignnone wp-image-7929\" src=\"https:\/\/soliton-gmbh.de\/wp-content\/uploads\/2024\/08\/4dtechnology-Logo-300x79.png\" alt=\"Twyman-Green interferometer from 4D Technology\" width=\"152\" height=\"40\" \/><\/a><\/em>","link":"https:\/\/soliton-gmbh.de\/en\/produkt-kategorie\/vermessungstechnik\/interferometrie\/interferometer-fuer-konkave-optiken-und-teleskopspiegel\/","name":"telescope mirror \/ optics measurement","slug":"interferometer-for-concave-optics-and-telescope-mirrors","taxonomy":"product_cat","parent":372,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Teleskopspiegel- \/ Optikvermessung - Soliton<\/title>\n<meta name=\"description\" content=\"Die Twyman-Green Interferometer von 4D Technology sind hochpr\u00e4zise optische Messinstrumente, die in Wissenschaft und Industrie vielseitig eingesetzt werden.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/soliton-gmbh.de\/en\/product-category\/surveying-technology\/interferometry\/interferometer-for-concave-optics-and-telescope-mirrors\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Teleskopspiegel- \/ Optikvermessung\" \/>\n<meta property=\"og:description\" content=\"Die Twyman-Green Interferometer von 4D Technology sind hochpr\u00e4zise optische Messinstrumente, die in Wissenschaft und Industrie vielseitig eingesetzt werden.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/soliton-gmbh.de\/en\/product-category\/surveying-technology\/interferometry\/interferometer-for-concave-optics-and-telescope-mirrors\/\" \/>\n<meta property=\"og:site_name\" content=\"Soliton Laser- und Messtechnik GmbH\" \/>\n<meta property=\"og:image\" content=\"https:\/\/soliton-gmbh.de\/wp-content\/uploads\/2024\/08\/4D15.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"844\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/soliton-gmbh.de\\\/produkt-kategorie\\\/vermessungstechnik\\\/interferometrie\\\/interferometer-fuer-konkave-optiken-und-teleskopspiegel\\\/\",\"url\":\"https:\\\/\\\/soliton-gmbh.de\\\/produkt-kategorie\\\/vermessungstechnik\\\/interferometrie\\\/interferometer-fuer-konkave-optiken-und-teleskopspiegel\\\/\",\"name\":\"Teleskopspiegel- \\\/ Optikvermessung - Soliton\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/soliton-gmbh.de\\\/#website\"},\"description\":\"Die Twyman-Green Interferometer von 4D Technology sind hochpr\u00e4zise optische Messinstrumente, die in Wissenschaft und Industrie vielseitig eingesetzt werden.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/soliton-gmbh.de\\\/produkt-kategorie\\\/vermessungstechnik\\\/interferometrie\\\/interferometer-fuer-konkave-optiken-und-teleskopspiegel\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/soliton-gmbh.de\\\/produkt-kategorie\\\/vermessungstechnik\\\/interferometrie\\\/interferometer-fuer-konkave-optiken-und-teleskopspiegel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/soliton-gmbh.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Messtechnik\",\"item\":\"https:\\\/\\\/soliton-gmbh.de\\\/produkt-kategorie\\\/vermessungstechnik\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Interferometrie\",\"item\":\"https:\\\/\\\/soliton-gmbh.de\\\/produkt-kategorie\\\/vermessungstechnik\\\/interferometrie\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Teleskopspiegel- \\\/ Optikvermessung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/soliton-gmbh.de\\\/#website\",\"url\":\"https:\\\/\\\/soliton-gmbh.de\\\/\",\"name\":\"Soliton Laser- und Messtechnik GmbH\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/soliton-gmbh.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/soliton-gmbh.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/soliton-gmbh.de\\\/#organization\",\"name\":\"Soliton GmbH\",\"url\":\"https:\\\/\\\/soliton-gmbh.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/soliton-gmbh.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/soliton-gmbh.de\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/cropped-soliton-logo.png\",\"contentUrl\":\"https:\\\/\\\/soliton-gmbh.de\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/cropped-soliton-logo.png\",\"width\":500,\"height\":350,\"caption\":\"Soliton GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/soliton-gmbh.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Telescope mirror \/ optics measurement - Soliton","description":"The Twyman-Green interferometers from 4D Technology are high-precision optical measuring instruments with a wide range of applications in science and industry.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/soliton-gmbh.de\/en\/product-category\/surveying-technology\/interferometry\/interferometer-for-concave-optics-and-telescope-mirrors\/","og_locale":"en_US","og_type":"article","og_title":"Teleskopspiegel- \/ Optikvermessung","og_description":"Die Twyman-Green Interferometer von 4D Technology sind hochpr\u00e4zise optische Messinstrumente, die in Wissenschaft und Industrie vielseitig eingesetzt werden.","og_url":"https:\/\/soliton-gmbh.de\/en\/product-category\/surveying-technology\/interferometry\/interferometer-for-concave-optics-and-telescope-mirrors\/","og_site_name":"Soliton Laser- und Messtechnik GmbH","og_image":[{"width":1500,"height":844,"url":"https:\/\/soliton-gmbh.de\/wp-content\/uploads\/2024\/08\/4D15.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/soliton-gmbh.de\/produkt-kategorie\/vermessungstechnik\/interferometrie\/interferometer-fuer-konkave-optiken-und-teleskopspiegel\/","url":"https:\/\/soliton-gmbh.de\/produkt-kategorie\/vermessungstechnik\/interferometrie\/interferometer-fuer-konkave-optiken-und-teleskopspiegel\/","name":"Telescope mirror \/ optics measurement - Soliton","isPartOf":{"@id":"https:\/\/soliton-gmbh.de\/#website"},"description":"The Twyman-Green interferometers from 4D Technology are high-precision optical measuring instruments with a wide range of applications in science and industry.","breadcrumb":{"@id":"https:\/\/soliton-gmbh.de\/produkt-kategorie\/vermessungstechnik\/interferometrie\/interferometer-fuer-konkave-optiken-und-teleskopspiegel\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/soliton-gmbh.de\/produkt-kategorie\/vermessungstechnik\/interferometrie\/interferometer-fuer-konkave-optiken-und-teleskopspiegel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/soliton-gmbh.de\/"},{"@type":"ListItem","position":2,"name":"Messtechnik","item":"https:\/\/soliton-gmbh.de\/produkt-kategorie\/vermessungstechnik\/"},{"@type":"ListItem","position":3,"name":"Interferometrie","item":"https:\/\/soliton-gmbh.de\/produkt-kategorie\/vermessungstechnik\/interferometrie\/"},{"@type":"ListItem","position":4,"name":"Teleskopspiegel- \/ Optikvermessung"}]},{"@type":"WebSite","@id":"https:\/\/soliton-gmbh.de\/#website","url":"https:\/\/soliton-gmbh.de\/","name":"Soliton Laser- und Messtechnik GmbH","description":"","publisher":{"@id":"https:\/\/soliton-gmbh.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/soliton-gmbh.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/soliton-gmbh.de\/#organization","name":"Soliton GmbH","url":"https:\/\/soliton-gmbh.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/soliton-gmbh.de\/#\/schema\/logo\/image\/","url":"https:\/\/soliton-gmbh.de\/wp-content\/uploads\/2022\/08\/cropped-soliton-logo.png","contentUrl":"https:\/\/soliton-gmbh.de\/wp-content\/uploads\/2022\/08\/cropped-soliton-logo.png","width":500,"height":350,"caption":"Soliton GmbH"},"image":{"@id":"https:\/\/soliton-gmbh.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/soliton-gmbh.de\/en\/wp-json\/wp\/v2\/product_cat\/685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soliton-gmbh.de\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/soliton-gmbh.de\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/soliton-gmbh.de\/en\/wp-json\/wp\/v2\/product_cat\/372"}],"wp:post_type":[{"href":"https:\/\/soliton-gmbh.de\/en\/wp-json\/wp\/v2\/product?product_cat=685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}