{"id":8585,"date":"2024-11-17T22:19:59","date_gmt":"2024-11-17T21:19:59","guid":{"rendered":"https:\/\/soliton-gmbh.de\/?post_type=glossary&#038;p=8585"},"modified":"2024-11-17T22:22:58","modified_gmt":"2024-11-17T21:22:58","slug":"tunable-ir-lasers-for-near-field-microscopy","status":"publish","type":"glossary","link":"https:\/\/soliton-gmbh.de\/en\/glossary\/durchstimmbare-ir-laser-fuer-die-nahfeldmikroskopie\/","title":{"rendered":"Tunable IR lasers for near-field microscopy"},"content":{"rendered":"<h1 class=\"wp-block-heading\" id=\"h-durchstimmbare-ir-laser-fur-die-nahfeldmikroskopie\"><a class=\"glossaryLink\"  href=\"https:\/\/soliton-gmbh.de\/en\/glossary\/durchstimmbare-ir-laser-fuer-die-nahfeldmikroskopie\/\"  data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'  tabindex='0' role='link'>Durchstimmbare IR-Laser f&uuml;r die Nahfeldmikroskopie<\/a><\/h1>\n\n\n\n<p>Das Wort &#x201E;Nano&#x201C; ist heutzutage allgegenw&#xE4;rtig und spielt in vielen wissenschaftlichen und industriellen Bereichen eine entscheidende Rolle. Einerseits beschreibt es eine geometrische Gr&#xF6;&#xDF;enordnung, andererseits weist es auf eine neue Generation von Partikeln hin. Nanopartikel besitzen durch ihre geringe Gr&#xF6;&#xDF;e einzigartige Eigenschaften, die in gr&#xF6;&#xDF;eren Partikeln desselben Materials nicht auftreten. Ob in Farben, Reinigungsmitteln oder Kompositmaterialien &#x2013; Wissenschaft und Industrie stehen gleicherma&#xDF;en vor der Herausforderung, diese Partikel und Makromolek&#xFC;le pr&#xE4;zise zu identifizieren, wobei Durchstimmbare IR-Laser eine wichtige Rolle spielen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Der Bedarf an pr&#xE4;zisen Identifikationsmethoden<\/h2>\n\n\n\n<p>Besonders bei der chemischen Identifizierung von Nanokompositmaterialien herrscht ein gro&#xDF;er Bedarf an pr&#xE4;zisen und materialspezifischen Verfahren. Lichtmikroskopie gilt als elegantes und zerst&#xF6;rungsfreies Verfahren, bei dem die Gefahr einer Strahlsch&#xE4;digung von biologischem Material nahezu ausgeschlossen ist. Allerdings st&#xF6;&#xDF;t diese Methode an ihre Grenzen, da die optische Aufl&#xF6;sung f&#xFC;r die Darstellung von Nanopartikeln nicht ausreicht.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/soliton-gmbh.de\/wp-content\/uploads\/2022\/12\/durchstimmbar-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"598\" height=\"304\" src=\"https:\/\/soliton-gmbh.de\/wp-content\/uploads\/2022\/12\/durchstimmbar-1.jpg\" alt=\"Durchstimmbare IR-Laser, AFM Mikroskop mit Tastspitze\" class=\"wp-image-5000\" srcset=\"https:\/\/soliton-gmbh.de\/wp-content\/uploads\/2022\/12\/durchstimmbar-1.jpg 598w, https:\/\/soliton-gmbh.de\/wp-content\/uploads\/2022\/12\/durchstimmbar-1-300x153.jpg 300w, https:\/\/soliton-gmbh.de\/wp-content\/uploads\/2022\/12\/durchstimmbar-1-18x9.jpg 18w\" sizes=\"auto, (max-width: 598px) 100vw, 598px\"\/><\/a><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Warum Infrarotspektroskopie an ihre Grenzen st&#xF6;&#xDF;t<\/h2>\n\n\n\n<p>Infrarotlicht wird h&#xE4;ufig zur Analyse chemischer Zusammensetzungen, Kristallstrukturen oder Dotierungen von Materialien eingesetzt. Doch auch die Infrarotspektroskopie hat ihre Einschr&#xE4;nkungen. Aufgrund ihrer r&#xE4;umlichen Aufl&#xF6;sungsgrenze von einigen Mikrometern ist sie f&#xFC;r die Darstellung von Nanopartikeln ungeeignet. Dabei w&#xE4;re die Analyse auf der Nanometerskala entscheidend, insbesondere bei neuartigen Nanokompositmaterialien oder biologischen Strukturen wie Zellmembranen und Makromolek&#xFC;len. Hier k&#xF6;nnten durchstimmbare IR-Laser zum Einsatz kommen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Revolution&#xE4;re Mikroskopie-Techniken<\/h3>\n\n\n\n<p>Die Arbeitsgruppe von Prof. Hillenbrand (CIC Nanogune und Neaspec) hat Mikroskopieverfahren entwickelt, die diese Herausforderungen &#xFC;berwinden. Diese Methoden basieren auf einem Kraftmikroskop (AFM), dessen Tastspitze als Kraft- und Streusonde dient. Ein durchstimmbarer CO2-Laser oder ein Quantenkaskadenlaser leitet Licht auf die Spitze, deren Durchmesser nur 10 nm betr&#xE4;gt. Das von der Spitze gestreute Licht liefert Informationen &#xFC;ber die Topographie, mechanische und lokale optische Eigenschaften der Probe. Durchstimmbare IR-Laser helfen dabei, diese Informationen pr&#xE4;zise zu gewinnen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/soliton-gmbh.de\/wp-content\/uploads\/2022\/12\/durchstimmbar-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"598\" height=\"304\" src=\"https:\/\/soliton-gmbh.de\/wp-content\/uploads\/2022\/12\/durchstimmbar-2.jpg\" alt=\"Durchstimmbare IR-Laser, CO2-Laser mit einem gro&#xDF;en Durchstimmbereich\" class=\"wp-image-5001\" srcset=\"https:\/\/soliton-gmbh.de\/wp-content\/uploads\/2022\/12\/durchstimmbar-2.jpg 598w, https:\/\/soliton-gmbh.de\/wp-content\/uploads\/2022\/12\/durchstimmbar-2-300x153.jpg 300w, https:\/\/soliton-gmbh.de\/wp-content\/uploads\/2022\/12\/durchstimmbar-2-18x9.jpg 18w\" sizes=\"auto, (max-width: 598px) 100vw, 598px\"\/><\/a><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">Die Vorteile der Nahfeldmikroskopie<\/h4>\n\n\n\n<p>Diese revolution&#xE4;re Technik bietet eine optische Aufl&#xF6;sung, die unabh&#xE4;ngig von der Wellenl&#xE4;nge des verwendeten Lichts ist. Stattdessen h&#xE4;ngt die Aufl&#xF6;sung ausschlie&#xDF;lich vom Spitzenradius der AFM-Sonde ab und liegt bei etwa 10 nm. Die Spitze wirkt dabei wie eine Antenne und fokussiert das eingestrahlte Licht auf einen extrem kleinen Bereich. Diese pr&#xE4;zise Beleuchtung erm&#xF6;glicht eine optische Nahfeldwechselwirkung zwischen Spitze und Probenoberfl&#xE4;che. Dadurch &#xE4;ndert sich die Intensit&#xE4;t des abgestrahlten Lichts abh&#xE4;ngig vom lokalen Brechungsindex der Probe. Durchstimmbaren IR-Lasern ist es zu verdanken, dass das Ergebnis ein optisches Bild mit einer Aufl&#xF6;sung ist, die nicht von den Grenzen der Beugung abh&#xE4;ngig ist.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Die Rolle durchstimmbarer IR-Laser<\/h3>\n\n\n\n<p>CO2-Laser mit einem gro&#xDF;en Durchstimmbereich von mehr als 1,5 &#xB5;m erweisen sich als ideale IR-Strahlungsquellen f&#xFC;r diese Anwendungen. Unsere Partner bei der <strong>ACCESS LASER COMPANY<\/strong> bieten L&#xF6;sungen zur Linienstabilisierung, einschlie&#xDF;lich eines Line-Trackers, der die Laserleistung sowie die longitudinale und transversale Modenstruktur stabilisiert. Dadurch wird die Anwendung durchstimmbarer IR-Laserquellen noch effizienter und pr&#xE4;ziser.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/soliton-gmbh.de\/wp-content\/uploads\/2022\/12\/durchstimmbar-3.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"598\" height=\"304\" src=\"https:\/\/soliton-gmbh.de\/wp-content\/uploads\/2022\/12\/durchstimmbar-3.jpg\" alt=\"Durchstimmbare IR-Laser, L&#xF6;sungen zur Linienstabilisierung, einschlie&#xDF;lich eines Line-Trackers, der die Laserleistung sowie die longitudinale und transversale Modenstruktur stabilisiert\" class=\"wp-image-5002\" srcset=\"https:\/\/soliton-gmbh.de\/wp-content\/uploads\/2022\/12\/durchstimmbar-3.jpg 598w, https:\/\/soliton-gmbh.de\/wp-content\/uploads\/2022\/12\/durchstimmbar-3-300x153.jpg 300w, https:\/\/soliton-gmbh.de\/wp-content\/uploads\/2022\/12\/durchstimmbar-3-18x9.jpg 18w\" sizes=\"auto, (max-width: 598px) 100vw, 598px\"\/><\/a><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Fazit<\/h2>\n\n\n\n<p>Durchstimmbare IR-Laserquellen er&#xF6;ffnen neue M&#xF6;glichkeiten in der Nahfeldmikroskopie und erweitern die Grenzen der optischen Analyse auf der Nanometerskala. Mit ihrer hohen Pr&#xE4;zision und Flexibilit&#xE4;t eignen sie sich ideal f&#xFC;r die chemische Identifizierung von Nanopartikeln und komplexen Materialien. Diese Technologien tragen wesentlich dazu bei, die Forschung und Entwicklung in Bereichen wie Materialwissenschaften und Biotechnologie voranzutreiben.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-weitere-artikel\">Weitere Artikel:<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/soliton-gmbh.de\/glossary\/berechnung-optischer-systeme\/\"><a class=\"glossaryLink\"  href=\"https:\/\/soliton-gmbh.de\/en\/glossary\/berechnung-optischer-systeme\/\"  data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'  tabindex='0' role='link'>Berechnung Optischer Systeme<\/a><\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/soliton-gmbh.de\/glossary\/rauhigkeitsmessung\/\"><a class=\"glossaryLink\"  href=\"https:\/\/soliton-gmbh.de\/en\/glossary\/rauhigkeitsmessung\/\"  data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'  tabindex='0' role='link'>Rauheitsmessung<\/a><\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/soliton-gmbh.de\/glossary\/spm-und-ters-messungen-an-graphen\/\"><a class=\"glossaryLink\"  href=\"https:\/\/soliton-gmbh.de\/en\/glossary\/spm-und-ters-messungen-an-graphen\/\"  data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'  tabindex='0' role='link'>SPM- und TERS-Messungen an Graphen<\/a><\/a><\/li>\n<\/ul>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p><a class=\"glossaryLink\" href=\"https:\/\/soliton-gmbh.de\/en\/glossary\/durchstimmbare-ir-laser-fuer-die-nahfeldmikroskopie\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Durchstimmbare IR-Laser f&#xFC;r die Nahfeldmikroskopie<\/a> Das Wort &#x201E;Nano&#x201C; ist heutzutage allgegenw&#xE4;rtig und spielt in vielen wissenschaftlichen und industriellen Bereichen eine entscheidende Rolle. Einerseits beschreibt es eine geometrische Gr&#xF6;&#xDF;enordnung, andererseits weist es auf eine neue Generation von Partikeln hin. Nanopartikel besitzen durch ihre geringe Gr&#xF6;&#xDF;e einzigartige Eigenschaften, die in gr&#xF6;&#xDF;eren Partikeln desselben Materials nicht auftreten. Ob [&#x2026;]<\/p>\n","protected":false},"author":9,"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-8585","glossary","type-glossary","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Durchstimmbare IR-Laser f\u00fcr die Nahfeldmikroskopie - Soliton Laser- und Messtechnik GmbH<\/title>\n<meta name=\"description\" content=\"Durchstimmbare IR-Laserquellen f\u00fcr die Nahfeldmikroskopie. Pr\u00e4zise Analyse von Nanopartikeln und Materialien auf der Nanometerskala.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/soliton-gmbh.de\/en\/glossary\/tunable-ir-lasers-for-near-field-microscopy\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Durchstimmbare IR-Laser f\u00fcr die Nahfeldmikroskopie\" \/>\n<meta property=\"og:description\" content=\"Durchstimmbare IR-Laserquellen f\u00fcr die Nahfeldmikroskopie. Pr\u00e4zise Analyse von Nanopartikeln und Materialien auf der Nanometerskala.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/soliton-gmbh.de\/en\/glossary\/tunable-ir-lasers-for-near-field-microscopy\/\" \/>\n<meta property=\"og:site_name\" content=\"Soliton Laser- und Messtechnik GmbH\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-17T21:22:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/soliton-gmbh.de\/wp-content\/uploads\/2022\/12\/durchstimmbar-1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/soliton-gmbh.de\\\/glossary\\\/durchstimmbare-ir-laser-fuer-die-nahfeldmikroskopie\\\/\",\"url\":\"https:\\\/\\\/soliton-gmbh.de\\\/glossary\\\/durchstimmbare-ir-laser-fuer-die-nahfeldmikroskopie\\\/\",\"name\":\"Durchstimmbare IR-Laser f\u00fcr die Nahfeldmikroskopie - Soliton Laser- und Messtechnik GmbH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/soliton-gmbh.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/soliton-gmbh.de\\\/glossary\\\/durchstimmbare-ir-laser-fuer-die-nahfeldmikroskopie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/soliton-gmbh.de\\\/glossary\\\/durchstimmbare-ir-laser-fuer-die-nahfeldmikroskopie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/soliton-gmbh.de\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/durchstimmbar-1.jpg\",\"datePublished\":\"2024-11-17T21:19:59+00:00\",\"dateModified\":\"2024-11-17T21:22:58+00:00\",\"description\":\"Durchstimmbare IR-Laserquellen f\u00fcr die Nahfeldmikroskopie. Pr\u00e4zise Analyse von Nanopartikeln und Materialien auf der Nanometerskala.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/soliton-gmbh.de\\\/glossary\\\/durchstimmbare-ir-laser-fuer-die-nahfeldmikroskopie\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/soliton-gmbh.de\\\/glossary\\\/durchstimmbare-ir-laser-fuer-die-nahfeldmikroskopie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/soliton-gmbh.de\\\/glossary\\\/durchstimmbare-ir-laser-fuer-die-nahfeldmikroskopie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/soliton-gmbh.de\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/durchstimmbar-1.jpg\",\"contentUrl\":\"https:\\\/\\\/soliton-gmbh.de\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/durchstimmbar-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/soliton-gmbh.de\\\/glossary\\\/durchstimmbare-ir-laser-fuer-die-nahfeldmikroskopie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/soliton-gmbh.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Durchstimmbare IR-Laser f\u00fcr die Nahfeldmikroskopie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/soliton-gmbh.de\\\/#website\",\"url\":\"https:\\\/\\\/soliton-gmbh.de\\\/\",\"name\":\"Soliton Laser- und Messtechnik GmbH\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/soliton-gmbh.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/soliton-gmbh.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/soliton-gmbh.de\\\/#organization\",\"name\":\"Soliton GmbH\",\"url\":\"https:\\\/\\\/soliton-gmbh.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/soliton-gmbh.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/soliton-gmbh.de\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/cropped-soliton-logo.png\",\"contentUrl\":\"https:\\\/\\\/soliton-gmbh.de\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/cropped-soliton-logo.png\",\"width\":500,\"height\":350,\"caption\":\"Soliton GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/soliton-gmbh.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tunable IR lasers for near-field microscopy - Soliton Laser- und Messtechnik GmbH","description":"Tunable IR laser sources for near-field microscopy. Precise analysis of nanoparticles and materials on the nanometer scale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/soliton-gmbh.de\/en\/glossary\/tunable-ir-lasers-for-near-field-microscopy\/","og_locale":"en_US","og_type":"article","og_title":"Durchstimmbare IR-Laser f\u00fcr die Nahfeldmikroskopie","og_description":"Durchstimmbare IR-Laserquellen f\u00fcr die Nahfeldmikroskopie. Pr\u00e4zise Analyse von Nanopartikeln und Materialien auf der Nanometerskala.","og_url":"https:\/\/soliton-gmbh.de\/en\/glossary\/tunable-ir-lasers-for-near-field-microscopy\/","og_site_name":"Soliton Laser- und Messtechnik GmbH","article_modified_time":"2024-11-17T21:22:58+00:00","og_image":[{"url":"https:\/\/soliton-gmbh.de\/wp-content\/uploads\/2022\/12\/durchstimmbar-1.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/soliton-gmbh.de\/glossary\/durchstimmbare-ir-laser-fuer-die-nahfeldmikroskopie\/","url":"https:\/\/soliton-gmbh.de\/glossary\/durchstimmbare-ir-laser-fuer-die-nahfeldmikroskopie\/","name":"Tunable IR lasers for near-field microscopy - Soliton Laser- und Messtechnik GmbH","isPartOf":{"@id":"https:\/\/soliton-gmbh.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/soliton-gmbh.de\/glossary\/durchstimmbare-ir-laser-fuer-die-nahfeldmikroskopie\/#primaryimage"},"image":{"@id":"https:\/\/soliton-gmbh.de\/glossary\/durchstimmbare-ir-laser-fuer-die-nahfeldmikroskopie\/#primaryimage"},"thumbnailUrl":"https:\/\/soliton-gmbh.de\/wp-content\/uploads\/2022\/12\/durchstimmbar-1.jpg","datePublished":"2024-11-17T21:19:59+00:00","dateModified":"2024-11-17T21:22:58+00:00","description":"Tunable IR laser sources for near-field microscopy. Precise analysis of nanoparticles and materials on the nanometer scale.","breadcrumb":{"@id":"https:\/\/soliton-gmbh.de\/glossary\/durchstimmbare-ir-laser-fuer-die-nahfeldmikroskopie\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/soliton-gmbh.de\/glossary\/durchstimmbare-ir-laser-fuer-die-nahfeldmikroskopie\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/soliton-gmbh.de\/glossary\/durchstimmbare-ir-laser-fuer-die-nahfeldmikroskopie\/#primaryimage","url":"https:\/\/soliton-gmbh.de\/wp-content\/uploads\/2022\/12\/durchstimmbar-1.jpg","contentUrl":"https:\/\/soliton-gmbh.de\/wp-content\/uploads\/2022\/12\/durchstimmbar-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/soliton-gmbh.de\/glossary\/durchstimmbare-ir-laser-fuer-die-nahfeldmikroskopie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/soliton-gmbh.de\/"},{"@type":"ListItem","position":2,"name":"Durchstimmbare IR-Laser f\u00fcr die Nahfeldmikroskopie"}]},{"@type":"WebSite","@id":"https:\/\/soliton-gmbh.de\/#website","url":"https:\/\/soliton-gmbh.de\/","name":"Soliton Laser- und Messtechnik GmbH","description":"","publisher":{"@id":"https:\/\/soliton-gmbh.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/soliton-gmbh.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/soliton-gmbh.de\/#organization","name":"Soliton GmbH","url":"https:\/\/soliton-gmbh.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/soliton-gmbh.de\/#\/schema\/logo\/image\/","url":"https:\/\/soliton-gmbh.de\/wp-content\/uploads\/2022\/08\/cropped-soliton-logo.png","contentUrl":"https:\/\/soliton-gmbh.de\/wp-content\/uploads\/2022\/08\/cropped-soliton-logo.png","width":500,"height":350,"caption":"Soliton GmbH"},"image":{"@id":"https:\/\/soliton-gmbh.de\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false,"woocommerce_thumbnail":false,"woocommerce_single":false,"woocommerce_gallery_thumbnail":false},"uagb_author_info":{"display_name":"Jonas Vogler","author_link":"https:\/\/soliton-gmbh.de\/en\/author\/jonas\/"},"uagb_comment_info":0,"uagb_excerpt":"Durchstimmbare IR-Laser f&uuml;r die Nahfeldmikroskopie Das Wort &bdquo;Nano&ldquo; ist heutzutage allgegenw&auml;rtig und spielt in vielen wissenschaftlichen und industriellen Bereichen eine entscheidende Rolle. Einerseits beschreibt es eine geometrische Gr&ouml;&szlig;enordnung, andererseits weist es auf eine neue Generation von Partikeln hin. Nanopartikel besitzen durch ihre geringe Gr&ouml;&szlig;e einzigartige Eigenschaften, die in gr&ouml;&szlig;eren Partikeln desselben Materials nicht auftreten. Ob&hellip;","_links":{"self":[{"href":"https:\/\/soliton-gmbh.de\/en\/wp-json\/wp\/v2\/glossary\/8585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soliton-gmbh.de\/en\/wp-json\/wp\/v2\/glossary"}],"about":[{"href":"https:\/\/soliton-gmbh.de\/en\/wp-json\/wp\/v2\/types\/glossary"}],"author":[{"embeddable":true,"href":"https:\/\/soliton-gmbh.de\/en\/wp-json\/wp\/v2\/users\/9"}],"version-history":[{"count":0,"href":"https:\/\/soliton-gmbh.de\/en\/wp-json\/wp\/v2\/glossary\/8585\/revisions"}],"wp:attachment":[{"href":"https:\/\/soliton-gmbh.de\/en\/wp-json\/wp\/v2\/media?parent=8585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}